{"id":47706,"date":"2025-08-25T10:58:07","date_gmt":"2025-08-25T08:58:07","guid":{"rendered":"https:\/\/www.icareweb.com\/training-sessions\/analyse-vibratoire-cat-ii-iso-18436-2-certifiante\/"},"modified":"2025-08-25T10:58:21","modified_gmt":"2025-08-25T08:58:21","slug":"analyse-vibratoire-cat-ii-iso-18436-2-certifiante","status":"publish","type":"training","link":"https:\/\/www.icareweb.com\/fr\/training-sessions\/analyse-vibratoire-cat-ii-iso-18436-2-certifiante\/","title":{"rendered":"ANALYSE VIBRATOIRE CAT II (ISO 18436-2) CERTIFIANTE"},"content":{"rendered":"\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Description<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<p>Avez-vous d\u00e9j\u00e0 particip\u00e9 depuis un certain temps \u00e0 un programme d\u2019analyse vibratoire dans votre \u00e9tablissement ? Savez-vous que vous pourriez faire davantage pour contribuer au succ\u00e8s de ce programme ? Avez-vous besoin d\u2019\u00e9largir vos connaissances ? Notre s\u00e9minaire ISO Cat\u00e9gorie II est la solution id\u00e9ale pour accomplir ces objectifs et bien plus encore !<\/p><p>Ce s\u00e9minaire de quatre jours s\u2019appuie sur le cours ISO Cat\u00e9gorie I et fournit les informations essentielles, de mani\u00e8re g\u00e9n\u00e9rale, pour mettre en \u0153uvre un programme de maintenance pr\u00e9dictive (PdM) r\u00e9ussi.<\/p><p>L\u2019accent est mis sur la d\u00e9tection d\u2019une s\u00e9rie de probl\u00e8mes fondamentaux de machines \u00e0 partir de notre tableau illustr\u00e9 de diagnostic vibratoire qui d\u00e9crit : (1) le d\u00e9s\u00e9quilibre, (2) le d\u00e9salignement, (3) l\u2019excentricit\u00e9 du rotor, (4) les jeux m\u00e9caniques, (5) les probl\u00e8mes de transmission par courroie et (6) les probl\u00e8mes de pied bancal, en utilisant \u00e0 la fois l\u2019analyse spectrale et l\u2019analyse de phase.<\/p><p>Des informations introductives sont \u00e9galement fournies pour la d\u00e9tection de r\u00e9sonance, de d\u00e9fauts de roulements \u00e0 rouleaux, d\u2019engrenages, de probl\u00e8mes li\u00e9s au d\u00e9bit et de d\u00e9fauts \u00e9lectriques.<\/p><p>Une proc\u00e9dure tabul\u00e9e \u00e9prouv\u00e9e, intitul\u00e9e \u00ab Comment sp\u00e9cifier des alarmes globales et par bandes spectrales significatives pour diff\u00e9rents types de machines et vitesses de fonctionnement \u00bb, montre clairement comment d\u00e9finir les seuils d\u2019alarme pour chaque bande de fr\u00e9quence.<\/p><p>Les pi\u00e8ges li\u00e9s aux mesures sont abord\u00e9s, ainsi que leur impact sur le diagnostic des probl\u00e8mes et l\u2019\u00e9valuation de leur gravit\u00e9.<\/p><p>Des \u00e9tudes de cas r\u00e9els sont pr\u00e9sent\u00e9es afin d\u2019illustrer clairement les m\u00e9thodes de diagnostic enseign\u00e9es.<\/p><p>Vous souhaitez approfondir vos connaissances mais ne savez pas par o\u00f9 commencer ? Notre cours Cat\u00e9gorie II est sp\u00e9cialement con\u00e7u pour s\u2019appuyer sur les bases apprises en Cat\u00e9gorie I et pour porter vos comp\u00e9tences en analyse vibratoire au niveau sup\u00e9rieur.<\/p><p>Le cours se termine par un examen qui, une fois r\u00e9ussi, certifie le participant en tant qu\u2019Analyste Vibratoire ISO Cat\u00e9gorie II.<\/p>\n\t\r\n\r\n\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Public recommand\u00e9<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<p>Ce cours est recommand\u00e9 aux analystes souhaitant \u00e9tudier les techniques et applications de l\u2019analyse vibratoire, ainsi qu\u2019aux responsables maintenance et ing\u00e9nieurs fiabilit\u00e9.<\/p>\n\t\r\n\r\n\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Objectifs d\u2019apprentissage<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<ul class=\"wp-block-list\"><li>Comprendre les principes fondamentaux de l&rsquo;analyse vibratoire appliqu&eacute;e &agrave; la maintenance pr&eacute;dictive<\/li><li>Apprendre &agrave; d&eacute;tecter les d&eacute;fauts courants des machines<\/li><li>&Ecirc;tre capable d&rsquo;utiliser l&rsquo;analyse spectrale et l&rsquo;analyse de phase pour identifier ces probl&egrave;mes<\/li><li>Savoir sp&eacute;cifier des alarmes globales et par bandes spectrales significatives pour diff&eacute;rents types de machines et diff&eacute;rentes vitesses de fonctionnement<\/li><li>&Ecirc;tre capable de d&eacute;finir les bandes de fr&eacute;quence, le nombre de lignes FFT, le nombre de moyennes et le param&egrave;tre vibratoire appropri&eacute; en fonction des caract&eacute;ristiques de la machine<\/li><li>Identifier les pi&egrave;ges courants lors des mesures et comprendre leur influence sur le diagnostic des d&eacute;fauts et l&rsquo;&eacute;valuation de leur gravit&eacute;<\/li><li>&Ecirc;tre capable d&rsquo;analyser et d&rsquo;interpr&eacute;ter des &eacute;tudes de cas r&eacute;els pour appliquer efficacement les m&eacute;thodes de diagnostic<\/li><li>Se pr&eacute;parer et obtenir la certification d&rsquo;Analyste Vibratoire ISO Cat&eacute;gorie II en r&eacute;ussissant l&rsquo;examen final<\/li><\/ul>\n\t\r\n\r\n\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Programme<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<ul class=\"wp-block-list\"><li>Introduction &agrave; l&rsquo;analyse vibratoire et &agrave; la maintenance pr&eacute;dictive<\/li><\/ul><ul class=\"wp-block-list\"><li>Qu&rsquo;est-ce que la vibration et comment peut-elle &ecirc;tre utilis&eacute;e pour &eacute;valuer l&rsquo;&eacute;tat des machines ?<\/li><\/ul><ul class=\"wp-block-list\"><li>Aper&ccedil;u des points forts et des limites des instruments typiques de mesure des vibrations<\/li><\/ul><p>\u00a0\u00a0\u00a0\u00a0\u2022 Qu\u2019est-ce que la fr\u00e9quence et comment se rapporte-t-elle \u00e0 une forme d\u2019onde temporelle ?<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Qu\u2019est-ce que le d\u00e9placement, la vitesse et l\u2019acc\u00e9l\u00e9ration des vibrations ?<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Comment convertir un param\u00e8tre de vibration en un autre (in\/sec en g, etc.)<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Qu\u2019est-ce que la phase ?<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Qu\u2019est-ce qu\u2019un spectre de vibration (aussi appel\u00e9 \u00ab FFT \u00bb ou \u00ab signature \u00bb)<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Effet du nombre de lignes FFT sur la pr\u00e9cision en fr\u00e9quence<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Diff\u00e9rence entre amplitude RMS, cr\u00eate et cr\u00eate-\u00e0-cr\u00eate et leur signification<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Quand utiliser le d\u00e9placement, la vitesse ou l\u2019acc\u00e9l\u00e9ration<\/p><p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u2022 Quelle est la limite acceptable pour la vibration ?<\/p><ul class=\"wp-block-list\"><li>Aper&ccedil;u des diff&eacute;rents capteurs de vibration et de leurs applications optimales<\/li><\/ul><ul class=\"wp-block-list\"><li>R&ocirc;le de l&rsquo;enveloppement haute fr&eacute;quence (HFE) et de la d&eacute;tection haute fr&eacute;quence (HFD) dans la d&eacute;tection et le suivi de certains d&eacute;fauts<\/li><\/ul><ul class=\"wp-block-list\"><li>Introduction &agrave; l&rsquo;analyse de la signature vibratoire et son utilisation pour &eacute;valuer l&rsquo;&eacute;tat de fonctionnement des machines<\/li><\/ul><p>\u00a0\u00a0\u00a0\u00a0\u2022 Pr\u00e9sentation du tableau illustr\u00e9 de diagnostic vibratoire sur 5 pages<\/p><ul class=\"wp-block-list\"><li>M&eacute;thode &eacute;prouv&eacute;e pour d&eacute;finir les niveaux d&rsquo;alarme par bandes spectrales et fr&eacute;quences &agrave; l&rsquo;aide des logiciels actuels de maintenance pr&eacute;dictive<\/li><\/ul><ul class=\"wp-block-list\"><li>Lignes directrices pour les tests d&rsquo;acceptation vibratoire des machines neuves ou r&eacute;nov&eacute;es<\/li><\/ul><ul class=\"wp-block-list\"><li>Principes de fonctionnement des machines courantes et emplacements recommand&eacute;s pour effectuer les mesures vibratoires<\/li><\/ul><ul class=\"wp-block-list\"><li>&Eacute;tudes de cas r&eacute;els en diagnostic vibratoire sur diff&eacute;rents types de machines<\/li><\/ul>\n\t\r\n\r\n\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Pr\u00e9requis<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<p>Il est recommand\u00e9 d\u2019avoir entre 3 et 6 mois d\u2019exp\u00e9rience sp\u00e9cifique en analyse vibratoire. Cependant, pour obtenir la certification d\u2019Analyste Vibratoire Cat\u00e9gorie II selon la norme ISO 18436, le participant doit disposer d\u2019au moins 18 mois d\u2019exp\u00e9rience pratique dans l\u2019application des techniques d\u2019analyse vibratoire. Si le participant ne poss\u00e8de pas cette exp\u00e9rience au moment de l\u2019examen, un certificat temporaire lui sera d\u00e9livr\u00e9. La certification compl\u00e8te sera accord\u00e9e une fois que les exigences d\u2019exp\u00e9rience professionnelle seront remplies.<\/p>\n\t\r\n\r\n\n\t\n<div class=\"wp-block-group icare-heading-whith-line is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-b25edd61 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading has-xx-large-font-size\">Dur\u00e9e de la formation<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide wp-container-content-9cfa9a5a\" style=\"margin-top:0.35em;margin-bottom:0;background-color:#27498c12;color:#27498c12\"\/>\n<\/div>\n\n\n\t<p>Cette formation s\u2019\u00e9tale sur quatre jours (examen le 5\u1d49 jour en matin\u00e9e).<\/p>\n\t","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","content-type":"","inline_featured_image":false},"training_category":[146],"class_list":{"0":"post-47706","1":"training","2":"type-training","3":"status-publish","5":"training_category-vibration"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.icareweb.com\/fr\/wp-json\/wp\/v2\/training\/47706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.icareweb.com\/fr\/wp-json\/wp\/v2\/training"}],"about":[{"href":"https:\/\/www.icareweb.com\/fr\/wp-json\/wp\/v2\/types\/training"}],"wp:attachment":[{"href":"https:\/\/www.icareweb.com\/fr\/wp-json\/wp\/v2\/media?parent=47706"}],"wp:term":[{"taxonomy":"training_category","embeddable":true,"href":"https:\/\/www.icareweb.com\/fr\/wp-json\/wp\/v2\/training_category?post=47706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}